{"id":5154,"date":"2024-08-12T16:35:34","date_gmt":"2024-08-12T14:35:34","guid":{"rendered":"https:\/\/enotourproject.org\/case\/innovazione-agricola-sostenibile\/"},"modified":"2026-07-21T18:25:00","modified_gmt":"2026-07-21T16:25:00","slug":"innovazione-agricola-sostenibile","status":"publish","type":"case","link":"https:\/\/enotourproject.org\/it\/case\/innovazione-agricola-sostenibile\/","title":{"rendered":"Innovazione agricola sostenibile"},"content":{"rendered":"<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1272_12e84f-13{margin-top:-30px;}.kb-row-layout-id1272_12e84f-13 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id1272_12e84f-13 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id1272_12e84f-13 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1272_12e84f-13{background-image:linear-gradient(135deg,var(--global-palette1) 3%,var(--global-palette4) 100%);}.kb-row-layout-id1272_12e84f-13 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1272_12e84f-13 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1272_12e84f-13 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1272_12e84f-13 aligncenter kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle\">\n<style>.kadence-column1272_ed044d-80 > .kt-inside-inner-col{display:flex;}.kadence-column1272_ed044d-80 > .kt-inside-inner-col,.kadence-column1272_ed044d-80 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1272_ed044d-80 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1272_ed044d-80 > .kt-inside-inner-col{flex-direction:column;align-items:center;}.kadence-column1272_ed044d-80 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column1272_ed044d-80 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column1272_ed044d-80 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1272_ed044d-80 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1272_ed044d-80{position:relative;}@media all and (max-width: 1024px){.kadence-column1272_ed044d-80 > .kt-inside-inner-col{flex-direction:column;align-items:center;}}@media all and (max-width: 767px){.kadence-column1272_ed044d-80 > .kt-inside-inner-col{flex-direction:column;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1272_ed044d-80\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1272_b20a20-5a, .wp-block-kadence-advancedheading.kt-adv-heading1272_b20a20-5a[data-kb-block=\"kb-adv-heading1272_b20a20-5a\"]{font-size:var(--global-kb-font-size-sm, 0.9rem);font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading1272_b20a20-5a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1272_b20a20-5a[data-kb-block=\"kb-adv-heading1272_b20a20-5a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h4 class=\"kt-adv-heading1272_b20a20-5a wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading1272_b20a20-5a\">CASO DI INNOVAZIONE &#8211; Sostenibilit\u00e0 ambientale<\/h4>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1272_7bfc22-10, .wp-block-kadence-advancedheading.kt-adv-heading1272_7bfc22-10[data-kb-block=\"kb-adv-heading1272_7bfc22-10\"]{font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading1272_7bfc22-10 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1272_7bfc22-10[data-kb-block=\"kb-adv-heading1272_7bfc22-10\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h2 class=\"kt-adv-heading1272_7bfc22-10 wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading1272_7bfc22-10\">Innovazione agricola sostenibile<\/h2>\n\n\n\n<p class=\"has-theme-palette-9-color has-text-color has-link-color wp-elements-1 wp-block-paragraph\">Un caso di studio su La Montecchia Conte Emo Capodilista<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1272_6eb67a-9b, .wp-block-kadence-advancedheading.kt-adv-heading1272_6eb67a-9b[data-kb-block=\"kb-adv-heading1272_6eb67a-9b\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1272_6eb67a-9b[data-kb-block=\"kb-adv-heading1272_6eb67a-9b\"]{display:flex;gap:0.25em;align-items:center;}.wp-block-kadence-advancedheading.kt-adv-heading1272_6eb67a-9b[data-kb-block=\"kb-adv-heading1272_6eb67a-9b\"] .kb-adv-heading-icon svg{width:1em;height:1em;}.wp-block-kadence-advancedheading.kt-adv-heading1272_6eb67a-9b mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1272_6eb67a-9b[data-kb-block=\"kb-adv-heading1272_6eb67a-9b\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style><p class=\"kt-adv-heading1272_6eb67a-9b wp-block-kadence-advancedheading kt-adv-heading-has-icon has-theme-palette9-color has-text-color\" data-kb-block=\"kb-adv-heading1272_6eb67a-9b\"><span class=\"kb-svg-icon-wrap kb-adv-heading-icon kb-svg-icon-fas_map-pin kb-adv-heading-icon-side-left\"><svg viewBox=\"0 0 288 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M112 316.94v156.69l22.02 33.02c4.75 7.12 15.22 7.12 19.97 0L176 473.63V316.94c-10.39 1.92-21.06 3.06-32 3.06s-21.61-1.14-32-3.06zM144 0C64.47 0 0 64.47 0 144s64.47 144 144 144 144-64.47 144-144S223.53 0 144 0zm0 76c-37.5 0-68 30.5-68 68 0 6.62-5.38 12-12 12s-12-5.38-12-12c0-50.73 41.28-92 92-92 6.62 0 12 5.38 12 12s-5.38 12-12 12z\"\/><\/svg><\/span><span class=\"kb-adv-text-inner\">Veneto, Italia<\/span><\/p><\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id1272_81a4dc-1d > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id1272_81a4dc-1d > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id1272_81a4dc-1d > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-none, 0rem );max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id1272_81a4dc-1d > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1272_81a4dc-1d > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1272_81a4dc-1d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1272_81a4dc-1d aligncenter has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column1272_825247-d3 > .kt-inside-inner-col,.kadence-column1272_825247-d3 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1272_825247-d3 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1272_825247-d3 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1272_825247-d3 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1272_825247-d3 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1272_825247-d3{position:relative;}@media all and (max-width: 1024px){.kadence-column1272_825247-d3 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1272_825247-d3 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1272_825247-d3\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1272_515b5b-6e .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1272_515b5b-6e .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:30px;border-top-right-radius:30px;border-bottom-right-radius:30px;border-bottom-left-radius:30px;padding-top:0px;padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:0px;padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-info-box1272_515b5b-6e .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1272_515b5b-6e .kt-info-svg-icon-flip, .kt-info-box1272_515b5b-6e .kt-blocks-info-box-number{font-size:20px;}.kt-info-box1272_515b5b-6e .kt-blocks-info-box-media{color:var(--global-palette4, #2D3748);border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box1272_515b5b-6e .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box1272_515b5b-6e .kt-infobox-textcontent h4.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1272_515b5b-6e .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette2, #2B6CB0);}.kt-info-box1272_515b5b-6e .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box1272_515b5b-6e .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box1272_515b5b-6e .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1272_515b5b-6e\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_calendar kt-info-svg-icon\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M0 0v2h7v-2h-7zm0 3v4.91c0 .05.04.09.09.09h6.81c.05 0 .09-.04.09-.09v-4.91h-7zm1 1h1v1h-1v-1zm2 0h1v1h-1v-1zm2 0h1v1h-1v-1zm-4 2h1v1h-1v-1zm2 0h1v1h-1v-1z\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><p class=\"kt-blocks-info-box-text\"><strong>Anno di inizio<\/strong>: 2012<\/p><\/div><\/span><\/div>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1272_428a2b-d9 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1272_428a2b-d9 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:30px;border-top-right-radius:30px;border-bottom-right-radius:30px;border-bottom-left-radius:30px;padding-top:0px;padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:0px;padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-info-box1272_428a2b-d9 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1272_428a2b-d9 .kt-info-svg-icon-flip, .kt-info-box1272_428a2b-d9 .kt-blocks-info-box-number{font-size:20px;}.kt-info-box1272_428a2b-d9 .kt-blocks-info-box-media{color:var(--global-palette4, #2D3748);border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box1272_428a2b-d9 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box1272_428a2b-d9 .kt-infobox-textcontent h4.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1272_428a2b-d9 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette2, #2B6CB0);}.kt-info-box1272_428a2b-d9 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box1272_428a2b-d9 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box1272_428a2b-d9 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1272_428a2b-d9\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_people kt-info-svg-icon\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M5.5 0c-.51 0-.95.35-1.22.88.45.54.72 1.28.72 2.13 0 .29-.03.55-.09.81.19.11.38.19.59.19.83 0 1.5-.9 1.5-2s-.67-2-1.5-2zm-3 1c-.83 0-1.5.9-1.5 2s.67 2 1.5 2 1.5-.9 1.5-2-.67-2-1.5-2zm4.75 3.16c-.43.51-1.02.82-1.69.84.27.38.44.84.44 1.34v.66h2v-1.66c0-.52-.31-.97-.75-1.19zm-6.5 1c-.44.22-.75.67-.75 1.19v1.66h5v-1.66c0-.52-.31-.97-.75-1.19-.45.53-1.06.84-1.75.84s-1.3-.32-1.75-.84z\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><p class=\"kt-blocks-info-box-text\"><strong>Soggetti coinvolti<\/strong>: Aziende vinicole<\/p><\/div><\/span><\/div>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1272_7fd8c4-8c .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1272_7fd8c4-8c .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:30px;border-top-right-radius:30px;border-bottom-right-radius:30px;border-bottom-left-radius:30px;padding-top:0px;padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:0px;padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-info-box1272_7fd8c4-8c .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1272_7fd8c4-8c .kt-info-svg-icon-flip, .kt-info-box1272_7fd8c4-8c .kt-blocks-info-box-number{font-size:20px;}.kt-info-box1272_7fd8c4-8c .kt-blocks-info-box-media{color:var(--global-palette4, #2D3748);border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box1272_7fd8c4-8c .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box1272_7fd8c4-8c .kt-infobox-textcontent h4.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1272_7fd8c4-8c .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette2, #2B6CB0);}.kt-info-box1272_7fd8c4-8c .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box1272_7fd8c4-8c .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box1272_7fd8c4-8c .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1272_7fd8c4-8c\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_graph kt-info-svg-icon\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M7.03 0l-3.03 3-1-1-3 3.03 1 1 2-2.03 1 1 4-4-.97-1zm-7.03 7v1h8v-1h-8z\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><p class=\"kt-blocks-info-box-text\"><strong>Area di innovazione<\/strong>: Sostenibilit\u00e0 ambientale<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1272_b61028-ce > .kt-inside-inner-col,.kadence-column1272_b61028-ce > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1272_b61028-ce > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1272_b61028-ce > .kt-inside-inner-col{flex-direction:column;}.kadence-column1272_b61028-ce > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1272_b61028-ce > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1272_b61028-ce{position:relative;}@media all and (max-width: 1024px){.kadence-column1272_b61028-ce > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1272_b61028-ce > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1272_b61028-ce\"><div class=\"kt-inside-inner-col\"><style>.kb-image1272_e670f5-89 .kb-image-has-overlay:after{opacity:0.3;}.kb-image1272_e670f5-89 img.kb-img, .kb-image1272_e670f5-89 .kb-img img{box-shadow:0px 0px 14px 0px rgba(0, 0, 0, 0.2);}<\/style>\n<div class=\"wp-block-kadence-image kb-image1272_e670f5-89\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/enotourproject.org\/wp-content\/uploads\/2024\/08\/place-holder-cases.jpg\" alt=\"\" class=\"kb-img wp-image-1945\" srcset=\"https:\/\/enotourproject.org\/wp-content\/uploads\/2024\/08\/place-holder-cases.jpg 400w, https:\/\/enotourproject.org\/wp-content\/uploads\/2024\/08\/place-holder-cases-300x300.jpg 300w, https:\/\/enotourproject.org\/wp-content\/uploads\/2024\/08\/place-holder-cases-150x150.jpg 150w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure><\/div>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id1272_3c4886-3f > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id1272_3c4886-3f > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id1272_3c4886-3f > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1272_3c4886-3f > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1272_3c4886-3f > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1272_3c4886-3f > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1272_3c4886-3f aligncenter wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column1272_cb6db5-56 > .kt-inside-inner-col,.kadence-column1272_cb6db5-56 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1272_cb6db5-56 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1272_cb6db5-56 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1272_cb6db5-56 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1272_cb6db5-56 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1272_cb6db5-56{position:relative;}@media all and (max-width: 1024px){.kadence-column1272_cb6db5-56 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1272_cb6db5-56 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1272_cb6db5-56\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1272_cd8db0-34, .wp-block-kadence-advancedheading.kt-adv-heading1272_cd8db0-34[data-kb-block=\"kb-adv-heading1272_cd8db0-34\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1272_cd8db0-34[data-kb-block=\"kb-adv-heading1272_cd8db0-34\"]{display:flex;gap:0.25em;align-items:center;}.wp-block-kadence-advancedheading.kt-adv-heading1272_cd8db0-34[data-kb-block=\"kb-adv-heading1272_cd8db0-34\"] .kb-adv-heading-icon svg{width:1em;height:1em;}.wp-block-kadence-advancedheading.kt-adv-heading1272_cd8db0-34[data-kb-block=\"kb-adv-heading1272_cd8db0-34\"] .kb-adv-heading-icon{font-size:43px;margin-right:var(--global-kb-spacing-xxs, 0.5rem);}.wp-block-kadence-advancedheading.kt-adv-heading1272_cd8db0-34 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1272_cd8db0-34[data-kb-block=\"kb-adv-heading1272_cd8db0-34\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style><h2 class=\"kt-adv-heading1272_cd8db0-34 wp-block-kadence-advancedheading kt-adv-heading-has-icon has-theme-palette4-color has-text-color\" data-kb-block=\"kb-adv-heading1272_cd8db0-34\"><span class=\"kb-svg-icon-wrap kb-adv-heading-icon kb-svg-icon-ic_minus kb-adv-heading-icon-side-left\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M0 0v2h8v-2h-8z\" transform=\"translate(0 3)\"\/><\/svg><\/span><span class=\"kb-adv-text-inner\"><strong>Obiettivi<\/strong><\/span><\/h2>\n\n\n<p class=\"has-text-align-left has-theme-palette-1-color has-text-color has-link-color wp-elements-2 wp-block-paragraph\">L&#8217;obiettivo \u00e8 ridurre al minimo l&#8217;impatto ambientale attraverso l&#8217;uso di fonti di energia rinnovabili, pratiche agricole sostenibili e tecnologie ecocompatibili. Queste iniziative mirano a ridurre le emissioni di carbonio, preservare le risorse naturali e promuovere la biodiversit\u00e0, garantendo la tutela dell&#8217;ambiente locale senza rinunciare alla qualit\u00e0 e alla tradizione dei propri prodotti agricoli. <\/p>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id1272_25c153-b2 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1272_25c153-b2 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1272_25c153-b2 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1272_25c153-b2 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1272_25c153-b2 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1272_25c153-b2 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1272_25c153-b2 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-row kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1272_946de0-ee > .kt-inside-inner-col,.kadence-column1272_946de0-ee > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1272_946de0-ee > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1272_946de0-ee > .kt-inside-inner-col{flex-direction:column;}.kadence-column1272_946de0-ee > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1272_946de0-ee > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1272_946de0-ee{position:relative;}@media all and (max-width: 1024px){.kadence-column1272_946de0-ee > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1272_946de0-ee > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1272_946de0-ee\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1272_06a0be-0e, .wp-block-kadence-advancedheading.kt-adv-heading1272_06a0be-0e[data-kb-block=\"kb-adv-heading1272_06a0be-0e\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1272_06a0be-0e[data-kb-block=\"kb-adv-heading1272_06a0be-0e\"]{display:flex;gap:0.25em;align-items:center;}.wp-block-kadence-advancedheading.kt-adv-heading1272_06a0be-0e[data-kb-block=\"kb-adv-heading1272_06a0be-0e\"] .kb-adv-heading-icon svg{width:1em;height:1em;}.wp-block-kadence-advancedheading.kt-adv-heading1272_06a0be-0e[data-kb-block=\"kb-adv-heading1272_06a0be-0e\"] .kb-adv-heading-icon{font-size:43px;margin-right:var(--global-kb-spacing-xxs, 0.5rem);}.wp-block-kadence-advancedheading.kt-adv-heading1272_06a0be-0e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1272_06a0be-0e[data-kb-block=\"kb-adv-heading1272_06a0be-0e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style><h2 class=\"kt-adv-heading1272_06a0be-0e wp-block-kadence-advancedheading kt-adv-heading-has-icon has-theme-palette4-color has-text-color\" data-kb-block=\"kb-adv-heading1272_06a0be-0e\"><span class=\"kb-svg-icon-wrap kb-adv-heading-icon kb-svg-icon-ic_minus kb-adv-heading-icon-side-left\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M0 0v2h8v-2h-8z\" transform=\"translate(0 3)\"\/><\/svg><\/span><span class=\"kb-adv-text-inner\"><strong>Sintesi<\/strong><\/span><\/h2><\/div><\/div>\n\n\n<style>.kadence-column1272_6bcd17-06 > .kt-inside-inner-col,.kadence-column1272_6bcd17-06 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1272_6bcd17-06 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1272_6bcd17-06 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1272_6bcd17-06 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1272_6bcd17-06 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1272_6bcd17-06{position:relative;}@media all and (max-width: 1024px){.kadence-column1272_6bcd17-06 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1272_6bcd17-06 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1272_6bcd17-06\"><div class=\"kt-inside-inner-col\">\n<p class=\"has-theme-palette-1-color has-text-color has-link-color wp-elements-3 wp-block-paragraph\">La Montecchia Conte Emo Capodilista ha intrapreso un percorso di trasformazione all\u2019insegna della sostenibilit\u00e0, stabilendo un nuovo standard nell\u2019agricoltura rispettosa dell\u2019ambiente. Dal 2012, il loro obiettivo \u00e8 stato quello di ridurre al minimo l\u2019impatto ambientale, mantenendo al contempo la qualit\u00e0 dei prodotti e la tradizione. Grazie a un approccio a tutto tondo che abbraccia energie rinnovabili, pratiche sostenibili e tecnologie ecocompatibili, non solo hanno ridotto le emissioni di carbonio, ma hanno anche preservato le risorse naturali e promosso la biodiversit\u00e0.  <\/p>\n\n\n\n<p class=\"has-theme-palette-1-color has-text-color has-link-color wp-elements-4 wp-block-paragraph\">Hanno integrato la sostenibilit\u00e0 ambientale nel DNA della loro attivit\u00e0. Questo impegno ha portato a risultati concreti, tra cui una riduzione dell\u2019impronta di carbonio, un miglioramento della salute del suolo e il riconoscimento, attraverso la certificazione biologica, del loro impegno ambientale. <\/p>\n\n\n\n<p class=\"has-theme-palette-1-color has-text-color has-link-color wp-elements-5 wp-block-paragraph\">Sono state messe in atto tante soluzioni innovative per raggiungere i loro obiettivi di sostenibilit\u00e0. Tra gli esempi ci sono la vinificazione e l\u2019invecchiamento con metodi naturali, l\u2019uso dell\u2019acqua sotterranea per l\u2019irrigazione del giardino, l\u2019allestimento dei vigneti con pali in legno di acacia, l\u2019imballaggio delle bottiglie in cartone riciclato, una stazione meteorologica alimentata da pannelli solari, l\u2019uso dei tralci di potatura per la rotazione delle balle, la messa a disposizione di punti di ricarica per le e-bike, un lago balneabile ecosostenibile e riscaldatori elettrici a basso consumo. Queste iniziative sottolineano il loro impegno verso la responsabilit\u00e0 ambientale e dimostrano la loro dedizione nell\u2019integrare pratiche eco-compatibili in ogni aspetto delle loro attivit\u00e0.  <\/p>\n\n\n\n<p class=\"has-theme-palette-1-color has-text-color has-link-color wp-elements-6 wp-block-paragraph\">In particolare, il loro approccio trasparente ha conquistato la fiducia e la soddisfazione dei consumatori, rafforzando la loro posizione di leader nell\u2019agricoltura sostenibile.<br\/>Il loro impegno all\u2019avanguardia non solo garantisce la resilienza delle loro attivit\u00e0 agricole, ma ispira anche altri a seguire il loro esempio nella salvaguardia del nostro pianeta per le generazioni future.<\/p>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id1272_367e3b-ea > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1272_367e3b-ea > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1272_367e3b-ea > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1272_367e3b-ea > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1272_367e3b-ea > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1272_367e3b-ea > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1272_367e3b-ea alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-row kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1272_daf9fb-db > .kt-inside-inner-col,.kadence-column1272_daf9fb-db > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1272_daf9fb-db > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1272_daf9fb-db > .kt-inside-inner-col{flex-direction:column;}.kadence-column1272_daf9fb-db > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1272_daf9fb-db > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1272_daf9fb-db{position:relative;}@media all and (max-width: 1024px){.kadence-column1272_daf9fb-db > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1272_daf9fb-db > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1272_daf9fb-db\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1272_1d8d21-d6, .wp-block-kadence-advancedheading.kt-adv-heading1272_1d8d21-d6[data-kb-block=\"kb-adv-heading1272_1d8d21-d6\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1272_1d8d21-d6[data-kb-block=\"kb-adv-heading1272_1d8d21-d6\"]{display:flex;gap:0.25em;align-items:center;}.wp-block-kadence-advancedheading.kt-adv-heading1272_1d8d21-d6[data-kb-block=\"kb-adv-heading1272_1d8d21-d6\"] .kb-adv-heading-icon svg{width:1em;height:1em;}.wp-block-kadence-advancedheading.kt-adv-heading1272_1d8d21-d6[data-kb-block=\"kb-adv-heading1272_1d8d21-d6\"] .kb-adv-heading-icon{font-size:43px;margin-right:var(--global-kb-spacing-xxs, 0.5rem);}.wp-block-kadence-advancedheading.kt-adv-heading1272_1d8d21-d6 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1272_1d8d21-d6[data-kb-block=\"kb-adv-heading1272_1d8d21-d6\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style><h2 class=\"kt-adv-heading1272_1d8d21-d6 wp-block-kadence-advancedheading kt-adv-heading-has-icon has-theme-palette4-color has-text-color\" data-kb-block=\"kb-adv-heading1272_1d8d21-d6\"><span class=\"kb-svg-icon-wrap kb-adv-heading-icon kb-svg-icon-ic_minus kb-adv-heading-icon-side-left\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M0 0v2h8v-2h-8z\" transform=\"translate(0 3)\"\/><\/svg><\/span><span class=\"kb-adv-text-inner\"><strong>Risultati<\/strong><\/span><\/h2><\/div><\/div>\n\n\n<style>.kadence-column1272_1798ec-66 > .kt-inside-inner-col,.kadence-column1272_1798ec-66 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1272_1798ec-66 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1272_1798ec-66 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1272_1798ec-66 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1272_1798ec-66 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1272_1798ec-66{position:relative;}@media all and (max-width: 1024px){.kadence-column1272_1798ec-66 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1272_1798ec-66 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1272_1798ec-66\"><div class=\"kt-inside-inner-col\">\n<ul class=\"wp-block-list has-theme-palette-1-color has-text-color has-link-color wp-elements-7\">\n<li>Riduzione dell&#8217;impronta di carbonio e dell&#8217;uso di sostanze chimiche<\/li>\n\n\n\n<li>Miglioramento della salute del suolo e della biodiversit\u00e0, con il risultato di prodotti biologici di alta qualit\u00e0<\/li>\n\n\n\n<li>Ha ottenuto la certificazione biologica e un riconoscimento per il suo impegno nella tutela dell&#8217;ambiente<\/li>\n\n\n\n<li>Maggiore efficienza nell&#8217;uso dell&#8217;acqua e nell&#8217;irrigazione<\/li>\n\n\n\n<li>Maggiore fiducia e soddisfazione dei consumatori grazie alla trasparenza e all&#8217;impegno nel rispetto degli standard ambientali e di qualit\u00e0 dei prodotti<\/li>\n\n\n\n<li>Sostenere la sostenibilit\u00e0 a lungo termine e la resilienza delle attivit\u00e0 agricole<\/li>\n<\/ul>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id1272_1d1b7f-f2 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1272_1d1b7f-f2 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1272_1d1b7f-f2 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1272_1d1b7f-f2 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1272_1d1b7f-f2 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1272_1d1b7f-f2 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1272_1d1b7f-f2 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1272_d96ba2-ad > .kt-inside-inner-col,.kadence-column1272_d96ba2-ad > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1272_d96ba2-ad > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1272_d96ba2-ad > .kt-inside-inner-col{flex-direction:column;}.kadence-column1272_d96ba2-ad > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1272_d96ba2-ad > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1272_d96ba2-ad{position:relative;}@media all and (max-width: 1024px){.kadence-column1272_d96ba2-ad > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1272_d96ba2-ad > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1272_d96ba2-ad\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns1272_15c84f-f0{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns1272_15c84f-f0 .kt-button{font-weight:normal;font-style:normal;}.kt-btns1272_15c84f-f0 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns1272_15c84f-f0 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns1272_15c84f-f0 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1272_15c84f-f0 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns1272_15c84f-f0 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns1272_15c84f-f0 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1272_15c84f-f0 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns1272_15c84f-f0\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn1272_e44f2e-a4.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn1272_e44f2e-a4.kb-button{background:#9b2b55;}@media all and (max-width: 1024px){.kb-btn1272_e44f2e-a4.kb-button .kb-svg-icon-wrap{display:block;}}<\/style><a class=\"kb-button kt-button button kb-btn1272_e44f2e-a4 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/lamontecchia.it\/en\/emo-capodilista\/sustainability\/\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"kt-btn-inner-text\">Maggiori informazioni<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"featured_media":5120,"template":"","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false},"innovation-area":[6],"region":[8],"class_list":["post-5154","case","type-case","status-publish","has-post-thumbnail","hentry","innovation-area-environmental-sustainability","region-veneto"],"acf":[],"taxonomy_info":{"innovation-area":[{"value":6,"label":"Environmental Sustainability"}],"region":[{"value":8,"label":"Veneto"}]},"featured_image_src_large":["https:\/\/enotourproject.org\/wp-content\/uploads\/2024\/08\/place-holder-cases-v.jpg",288,188,false],"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/enotourproject.org\/it\/wp-json\/wp\/v2\/case\/5154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enotourproject.org\/it\/wp-json\/wp\/v2\/case"}],"about":[{"href":"https:\/\/enotourproject.org\/it\/wp-json\/wp\/v2\/types\/case"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/enotourproject.org\/it\/wp-json\/wp\/v2\/media\/5120"}],"wp:attachment":[{"href":"https:\/\/enotourproject.org\/it\/wp-json\/wp\/v2\/media?parent=5154"}],"wp:term":[{"taxonomy":"innovation-area","embeddable":true,"href":"https:\/\/enotourproject.org\/it\/wp-json\/wp\/v2\/innovation-area?post=5154"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/enotourproject.org\/it\/wp-json\/wp\/v2\/region?post=5154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}