{"id":5146,"date":"2024-08-12T16:41:13","date_gmt":"2024-08-12T14:41:13","guid":{"rendered":"https:\/\/enotourproject.org\/case\/ca-di-rajo\/"},"modified":"2026-07-21T18:14:55","modified_gmt":"2026-07-21T16:14:55","slug":"ca-di-rajo","status":"publish","type":"case","link":"https:\/\/enotourproject.org\/fr\/case\/ca-di-rajo\/","title":{"rendered":"Ca\u2019 di Rajo"},"content":{"rendered":"<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1275_83c613-22{margin-top:-30px;}.kb-row-layout-id1275_83c613-22 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id1275_83c613-22 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id1275_83c613-22 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1275_83c613-22{background-image:linear-gradient(135deg,var(--global-palette1) 3%,var(--global-palette4) 100%);}.kb-row-layout-id1275_83c613-22 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1275_83c613-22 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1275_83c613-22 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1275_83c613-22 aligncenter kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle\">\n<style>.kadence-column1275_a7f7ee-7f > .kt-inside-inner-col{display:flex;}.kadence-column1275_a7f7ee-7f > .kt-inside-inner-col,.kadence-column1275_a7f7ee-7f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1275_a7f7ee-7f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1275_a7f7ee-7f > .kt-inside-inner-col{flex-direction:column;align-items:center;}.kadence-column1275_a7f7ee-7f > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column1275_a7f7ee-7f > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column1275_a7f7ee-7f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1275_a7f7ee-7f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1275_a7f7ee-7f{position:relative;}@media all and (max-width: 1024px){.kadence-column1275_a7f7ee-7f > .kt-inside-inner-col{flex-direction:column;align-items:center;}}@media all and (max-width: 767px){.kadence-column1275_a7f7ee-7f > .kt-inside-inner-col{flex-direction:column;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1275_a7f7ee-7f\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1275_275350-04, .wp-block-kadence-advancedheading.kt-adv-heading1275_275350-04[data-kb-block=\"kb-adv-heading1275_275350-04\"]{font-size:var(--global-kb-font-size-sm, 0.9rem);font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading1275_275350-04 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1275_275350-04[data-kb-block=\"kb-adv-heading1275_275350-04\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h4 class=\"kt-adv-heading1275_275350-04 wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading1275_275350-04\">EXEMPLE D&rsquo;INNOVATION &#8211; Marketing, exp\u00e9riences et services | Accessibilit\u00e9 et inclusion<\/h4>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1275_1a678a-12, .wp-block-kadence-advancedheading.kt-adv-heading1275_1a678a-12[data-kb-block=\"kb-adv-heading1275_1a678a-12\"]{font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading1275_1a678a-12 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1275_1a678a-12[data-kb-block=\"kb-adv-heading1275_1a678a-12\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h2 class=\"kt-adv-heading1275_1a678a-12 wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading1275_1a678a-12\">Ca\u2019 di Rajo<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1275_64805b-9e, .wp-block-kadence-advancedheading.kt-adv-heading1275_64805b-9e[data-kb-block=\"kb-adv-heading1275_64805b-9e\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1275_64805b-9e[data-kb-block=\"kb-adv-heading1275_64805b-9e\"]{display:flex;gap:0.25em;align-items:center;}.wp-block-kadence-advancedheading.kt-adv-heading1275_64805b-9e[data-kb-block=\"kb-adv-heading1275_64805b-9e\"] .kb-adv-heading-icon svg{width:1em;height:1em;}.wp-block-kadence-advancedheading.kt-adv-heading1275_64805b-9e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1275_64805b-9e[data-kb-block=\"kb-adv-heading1275_64805b-9e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style><p class=\"kt-adv-heading1275_64805b-9e wp-block-kadence-advancedheading kt-adv-heading-has-icon has-theme-palette9-color has-text-color\" data-kb-block=\"kb-adv-heading1275_64805b-9e\"><span class=\"kb-svg-icon-wrap kb-adv-heading-icon kb-svg-icon-fas_map-pin kb-adv-heading-icon-side-left\"><svg viewBox=\"0 0 288 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M112 316.94v156.69l22.02 33.02c4.75 7.12 15.22 7.12 19.97 0L176 473.63V316.94c-10.39 1.92-21.06 3.06-32 3.06s-21.61-1.14-32-3.06zM144 0C64.47 0 0 64.47 0 144s64.47 144 144 144 144-64.47 144-144S223.53 0 144 0zm0 76c-37.5 0-68 30.5-68 68 0 6.62-5.38 12-12 12s-12-5.38-12-12c0-50.73 41.28-92 92-92 6.62 0 12 5.38 12 12s-5.38 12-12 12z\"\/><\/svg><\/span><span class=\"kb-adv-text-inner\">San Polo di Piave, V\u00e9n\u00e9tie, Italie<\/span><\/p><\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id1275_7a7035-ea > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id1275_7a7035-ea > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id1275_7a7035-ea > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-none, 0rem );max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id1275_7a7035-ea > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1275_7a7035-ea > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1275_7a7035-ea > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1275_7a7035-ea aligncenter has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column1275_e8cc7b-3d > .kt-inside-inner-col,.kadence-column1275_e8cc7b-3d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1275_e8cc7b-3d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1275_e8cc7b-3d > .kt-inside-inner-col{flex-direction:column;}.kadence-column1275_e8cc7b-3d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1275_e8cc7b-3d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1275_e8cc7b-3d{position:relative;}@media all and (max-width: 1024px){.kadence-column1275_e8cc7b-3d > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1275_e8cc7b-3d > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1275_e8cc7b-3d\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1275_f132b6-b4 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1275_f132b6-b4 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:30px;border-top-right-radius:30px;border-bottom-right-radius:30px;border-bottom-left-radius:30px;padding-top:0px;padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:0px;padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-info-box1275_f132b6-b4 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1275_f132b6-b4 .kt-info-svg-icon-flip, .kt-info-box1275_f132b6-b4 .kt-blocks-info-box-number{font-size:20px;}.kt-info-box1275_f132b6-b4 .kt-blocks-info-box-media{color:var(--global-palette4, #2D3748);border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box1275_f132b6-b4 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box1275_f132b6-b4 .kt-infobox-textcontent h4.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1275_f132b6-b4 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette2, #2B6CB0);}.kt-info-box1275_f132b6-b4 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box1275_f132b6-b4 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box1275_f132b6-b4 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1275_f132b6-b4\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_calendar kt-info-svg-icon\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M0 0v2h7v-2h-7zm0 3v4.91c0 .05.04.09.09.09h6.81c.05 0 .09-.04.09-.09v-4.91h-7zm1 1h1v1h-1v-1zm2 0h1v1h-1v-1zm2 0h1v1h-1v-1zm-4 2h1v1h-1v-1zm2 0h1v1h-1v-1z\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><p class=\"kt-blocks-info-box-text\"><strong>Ann\u00e9e de d\u00e9but<\/strong>:  <\/p><\/div><\/span><\/div>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1275_e8c26f-e3 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1275_e8c26f-e3 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:30px;border-top-right-radius:30px;border-bottom-right-radius:30px;border-bottom-left-radius:30px;padding-top:0px;padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:0px;padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-info-box1275_e8c26f-e3 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1275_e8c26f-e3 .kt-info-svg-icon-flip, .kt-info-box1275_e8c26f-e3 .kt-blocks-info-box-number{font-size:20px;}.kt-info-box1275_e8c26f-e3 .kt-blocks-info-box-media{color:var(--global-palette4, #2D3748);border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box1275_e8c26f-e3 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box1275_e8c26f-e3 .kt-infobox-textcontent h4.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1275_e8c26f-e3 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette2, #2B6CB0);}.kt-info-box1275_e8c26f-e3 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box1275_e8c26f-e3 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box1275_e8c26f-e3 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1275_e8c26f-e3\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_people kt-info-svg-icon\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M5.5 0c-.51 0-.95.35-1.22.88.45.54.72 1.28.72 2.13 0 .29-.03.55-.09.81.19.11.38.19.59.19.83 0 1.5-.9 1.5-2s-.67-2-1.5-2zm-3 1c-.83 0-1.5.9-1.5 2s.67 2 1.5 2 1.5-.9 1.5-2-.67-2-1.5-2zm4.75 3.16c-.43.51-1.02.82-1.69.84.27.38.44.84.44 1.34v.66h2v-1.66c0-.52-.31-.97-.75-1.19zm-6.5 1c-.44.22-.75.67-.75 1.19v1.66h5v-1.66c0-.52-.31-.97-.75-1.19-.45.53-1.06.84-1.75.84s-1.3-.32-1.75-.84z\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><p class=\"kt-blocks-info-box-text\"><strong>Th\u00e8mes abord\u00e9s<\/strong>: Cave \u00e0 vin<\/p><\/div><\/span><\/div>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1275_bb66b0-f6 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1275_bb66b0-f6 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:30px;border-top-right-radius:30px;border-bottom-right-radius:30px;border-bottom-left-radius:30px;padding-top:0px;padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:0px;padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-info-box1275_bb66b0-f6 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1275_bb66b0-f6 .kt-info-svg-icon-flip, .kt-info-box1275_bb66b0-f6 .kt-blocks-info-box-number{font-size:20px;}.kt-info-box1275_bb66b0-f6 .kt-blocks-info-box-media{color:var(--global-palette4, #2D3748);border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box1275_bb66b0-f6 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box1275_bb66b0-f6 .kt-infobox-textcontent h4.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1275_bb66b0-f6 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette2, #2B6CB0);}.kt-info-box1275_bb66b0-f6 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box1275_bb66b0-f6 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box1275_bb66b0-f6 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1275_bb66b0-f6\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_graph kt-info-svg-icon\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M7.03 0l-3.03 3-1-1-3 3.03 1 1 2-2.03 1 1 4-4-.97-1zm-7.03 7v1h8v-1h-8z\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><p class=\"kt-blocks-info-box-text\"><strong>Domaine d&rsquo;innovation<\/strong>: Marketing | Accessibilit\u00e9 et inclusion<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1275_5650d3-26 > .kt-inside-inner-col,.kadence-column1275_5650d3-26 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1275_5650d3-26 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1275_5650d3-26 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1275_5650d3-26 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1275_5650d3-26 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1275_5650d3-26{position:relative;}@media all and (max-width: 1024px){.kadence-column1275_5650d3-26 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1275_5650d3-26 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1275_5650d3-26\"><div class=\"kt-inside-inner-col\"><style>.kb-image1275_32447f-ac .kb-image-has-overlay:after{opacity:0.3;}.kb-image1275_32447f-ac img.kb-img, .kb-image1275_32447f-ac .kb-img img{box-shadow:0px 0px 14px 0px rgba(0, 0, 0, 0.2);}<\/style>\n<div class=\"wp-block-kadence-image kb-image1275_32447f-ac\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/enotourproject.org\/wp-content\/uploads\/2024\/08\/place-holder-cases.jpg\" alt=\"\" class=\"kb-img wp-image-1945\" srcset=\"https:\/\/enotourproject.org\/wp-content\/uploads\/2024\/08\/place-holder-cases.jpg 400w, https:\/\/enotourproject.org\/wp-content\/uploads\/2024\/08\/place-holder-cases-300x300.jpg 300w, https:\/\/enotourproject.org\/wp-content\/uploads\/2024\/08\/place-holder-cases-150x150.jpg 150w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure><\/div>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id1275_442e9c-84 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id1275_442e9c-84 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id1275_442e9c-84 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1275_442e9c-84 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1275_442e9c-84 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1275_442e9c-84 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1275_442e9c-84 aligncenter wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column1275_c02ed2-00 > .kt-inside-inner-col,.kadence-column1275_c02ed2-00 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1275_c02ed2-00 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1275_c02ed2-00 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1275_c02ed2-00 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1275_c02ed2-00 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1275_c02ed2-00{position:relative;}@media all and (max-width: 1024px){.kadence-column1275_c02ed2-00 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1275_c02ed2-00 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1275_c02ed2-00\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1275_d8f7a7-0e, .wp-block-kadence-advancedheading.kt-adv-heading1275_d8f7a7-0e[data-kb-block=\"kb-adv-heading1275_d8f7a7-0e\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1275_d8f7a7-0e[data-kb-block=\"kb-adv-heading1275_d8f7a7-0e\"]{display:flex;gap:0.25em;align-items:center;}.wp-block-kadence-advancedheading.kt-adv-heading1275_d8f7a7-0e[data-kb-block=\"kb-adv-heading1275_d8f7a7-0e\"] .kb-adv-heading-icon svg{width:1em;height:1em;}.wp-block-kadence-advancedheading.kt-adv-heading1275_d8f7a7-0e[data-kb-block=\"kb-adv-heading1275_d8f7a7-0e\"] .kb-adv-heading-icon{font-size:43px;margin-right:var(--global-kb-spacing-xxs, 0.5rem);}.wp-block-kadence-advancedheading.kt-adv-heading1275_d8f7a7-0e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1275_d8f7a7-0e[data-kb-block=\"kb-adv-heading1275_d8f7a7-0e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style><h2 class=\"kt-adv-heading1275_d8f7a7-0e wp-block-kadence-advancedheading kt-adv-heading-has-icon has-theme-palette4-color has-text-color\" data-kb-block=\"kb-adv-heading1275_d8f7a7-0e\"><span class=\"kb-svg-icon-wrap kb-adv-heading-icon kb-svg-icon-ic_minus kb-adv-heading-icon-side-left\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M0 0v2h8v-2h-8z\" transform=\"translate(0 3)\"\/><\/svg><\/span><span class=\"kb-adv-text-inner\"><strong>Objectifs<\/strong><\/span><\/h2>\n\n\n<p class=\"has-theme-palette-1-color has-text-color has-link-color wp-elements-1 wp-block-paragraph\">Rendre l&rsquo;\u0153notourisme accessible aux personnes en situation de handicap et am\u00e9liorer l&rsquo;exp\u00e9rience \u0153notouristique globale pour l&rsquo;ensemble de la client\u00e8le.<\/p>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id1275_b0546b-98 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1275_b0546b-98 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1275_b0546b-98 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1275_b0546b-98 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1275_b0546b-98 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1275_b0546b-98 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1275_b0546b-98 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-row kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1275_7ca5ca-02 > .kt-inside-inner-col,.kadence-column1275_7ca5ca-02 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1275_7ca5ca-02 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1275_7ca5ca-02 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1275_7ca5ca-02 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1275_7ca5ca-02 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1275_7ca5ca-02{position:relative;}@media all and (max-width: 1024px){.kadence-column1275_7ca5ca-02 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1275_7ca5ca-02 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1275_7ca5ca-02\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1275_0d5c2b-99, .wp-block-kadence-advancedheading.kt-adv-heading1275_0d5c2b-99[data-kb-block=\"kb-adv-heading1275_0d5c2b-99\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1275_0d5c2b-99[data-kb-block=\"kb-adv-heading1275_0d5c2b-99\"]{display:flex;gap:0.25em;align-items:center;}.wp-block-kadence-advancedheading.kt-adv-heading1275_0d5c2b-99[data-kb-block=\"kb-adv-heading1275_0d5c2b-99\"] .kb-adv-heading-icon svg{width:1em;height:1em;}.wp-block-kadence-advancedheading.kt-adv-heading1275_0d5c2b-99[data-kb-block=\"kb-adv-heading1275_0d5c2b-99\"] .kb-adv-heading-icon{font-size:43px;margin-right:var(--global-kb-spacing-xxs, 0.5rem);}.wp-block-kadence-advancedheading.kt-adv-heading1275_0d5c2b-99 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1275_0d5c2b-99[data-kb-block=\"kb-adv-heading1275_0d5c2b-99\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style><h2 class=\"kt-adv-heading1275_0d5c2b-99 wp-block-kadence-advancedheading kt-adv-heading-has-icon has-theme-palette4-color has-text-color\" data-kb-block=\"kb-adv-heading1275_0d5c2b-99\"><span class=\"kb-svg-icon-wrap kb-adv-heading-icon kb-svg-icon-ic_minus kb-adv-heading-icon-side-left\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M0 0v2h8v-2h-8z\" transform=\"translate(0 3)\"\/><\/svg><\/span><span class=\"kb-adv-text-inner\"><strong>R\u00e9sum\u00e9<\/strong><\/span><\/h2><\/div><\/div>\n\n\n<style>.kadence-column1275_cf5c58-78 > .kt-inside-inner-col,.kadence-column1275_cf5c58-78 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1275_cf5c58-78 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1275_cf5c58-78 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1275_cf5c58-78 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1275_cf5c58-78 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1275_cf5c58-78{position:relative;}@media all and (max-width: 1024px){.kadence-column1275_cf5c58-78 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1275_cf5c58-78 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1275_cf5c58-78\"><div class=\"kt-inside-inner-col\">\n<p class=\"has-theme-palette-1-color has-text-color has-link-color wp-elements-2 wp-block-paragraph\">Le domaine viticole Ca\u2019 di Rajo a mis en place plusieurs initiatives visant \u00e0 am\u00e9liorer son offre \u0153notouristique, ax\u00e9es notamment sur l\u2019accessibilit\u00e9, sans toutefois s\u2019y limiter.<br\/>Tout d\u2019abord, il a mis en place des visites multisensorielles, telles que des parcours tactiles et des d\u00e9gustations sensorielles. Les cartes tactiles sont con\u00e7ues pour offrir une exp\u00e9rience inclusive et immersive aux visiteurs, en particulier \u00e0 ceux qui souffrent d\u2019un handicap visuel. Ce projet int\u00e8gre des exp\u00e9riences sensorielles qui vont au-del\u00e0 de la vue, permettant aux visiteurs de d\u00e9couvrir le domaine et ses environs par le toucher, l\u2019odorat et l\u2019ou\u00efe. La d\u00e9gustation sensorielle, quant \u00e0 elle, est con\u00e7ue pour mettre en valeur les ar\u00f4mes et les saveurs, aidant ainsi les visiteurs \u00e0 se concentrer sur les aspects sensoriels du vin.   <\/p>\n\n\n\n<p class=\"has-theme-palette-1-color has-text-color has-link-color wp-elements-3 wp-block-paragraph\">D&rsquo;autre part, ils ont recours \u00e0 des technologies de pointe telles que des audioguides interactifs et des applications. Le domaine viticole propose en effet des audioguides qui d\u00e9crivent l&rsquo;histoire, le processus de vinification et les caract\u00e9ristiques des vins. Ces audioguides sont disponibles en plusieurs langues et s&rsquo;av\u00e8rent utiles tant pour les personnes malvoyantes que pour celles qui pr\u00e9f\u00e8rent une exp\u00e9rience plus autonome. Une application mobile a \u00e9galement \u00e9t\u00e9 mise en place afin de fournir des informations vocales et visuelles en temps r\u00e9el, am\u00e9liorant ainsi l\u2019accessibilit\u00e9 pour les personnes souffrant de d\u00e9ficiences auditives et visuelles.   <\/p>\n\n\n\n<p class=\"has-theme-palette-1-color has-text-color has-link-color wp-elements-4 wp-block-paragraph\">Troisi\u00e8mement, l&rsquo;accessibilit\u00e9 physique rev\u00eat \u00e9galement une importance particuli\u00e8re pour la cave. Celle-ci est \u00e9quip\u00e9e de toilettes, de rampes d&rsquo;acc\u00e8s et d&rsquo;ascenseurs qui facilitent l&rsquo;acc\u00e8s aux diff\u00e9rents espaces du site pour les personnes \u00e0 mobilit\u00e9 r\u00e9duite. <\/p>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id1275_6b000b-6c > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1275_6b000b-6c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1275_6b000b-6c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1275_6b000b-6c > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1275_6b000b-6c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1275_6b000b-6c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1275_6b000b-6c alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-row kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1275_2fd393-5d > .kt-inside-inner-col,.kadence-column1275_2fd393-5d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1275_2fd393-5d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1275_2fd393-5d > .kt-inside-inner-col{flex-direction:column;}.kadence-column1275_2fd393-5d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1275_2fd393-5d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1275_2fd393-5d{position:relative;}@media all and (max-width: 1024px){.kadence-column1275_2fd393-5d > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1275_2fd393-5d > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1275_2fd393-5d\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1275_9e31fe-37, .wp-block-kadence-advancedheading.kt-adv-heading1275_9e31fe-37[data-kb-block=\"kb-adv-heading1275_9e31fe-37\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1275_9e31fe-37[data-kb-block=\"kb-adv-heading1275_9e31fe-37\"]{display:flex;gap:0.25em;align-items:center;}.wp-block-kadence-advancedheading.kt-adv-heading1275_9e31fe-37[data-kb-block=\"kb-adv-heading1275_9e31fe-37\"] .kb-adv-heading-icon svg{width:1em;height:1em;}.wp-block-kadence-advancedheading.kt-adv-heading1275_9e31fe-37[data-kb-block=\"kb-adv-heading1275_9e31fe-37\"] .kb-adv-heading-icon{font-size:43px;margin-right:var(--global-kb-spacing-xxs, 0.5rem);}.wp-block-kadence-advancedheading.kt-adv-heading1275_9e31fe-37 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1275_9e31fe-37[data-kb-block=\"kb-adv-heading1275_9e31fe-37\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style><h2 class=\"kt-adv-heading1275_9e31fe-37 wp-block-kadence-advancedheading kt-adv-heading-has-icon has-theme-palette4-color has-text-color\" data-kb-block=\"kb-adv-heading1275_9e31fe-37\"><span class=\"kb-svg-icon-wrap kb-adv-heading-icon kb-svg-icon-ic_minus kb-adv-heading-icon-side-left\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M0 0v2h8v-2h-8z\" transform=\"translate(0 3)\"\/><\/svg><\/span><span class=\"kb-adv-text-inner\"><strong>R\u00e9sultats<\/strong><\/span><\/h2><\/div><\/div>\n\n\n<style>.kadence-column1275_f0acba-dc > .kt-inside-inner-col,.kadence-column1275_f0acba-dc > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1275_f0acba-dc > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1275_f0acba-dc > .kt-inside-inner-col{flex-direction:column;}.kadence-column1275_f0acba-dc > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1275_f0acba-dc > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1275_f0acba-dc{position:relative;}@media all and (max-width: 1024px){.kadence-column1275_f0acba-dc > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1275_f0acba-dc > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1275_f0acba-dc\"><div class=\"kt-inside-inner-col\">\n<p class=\"has-theme-palette-1-color has-text-color has-link-color wp-elements-5 wp-block-paragraph\">Les services propos\u00e9s garantissent que l&rsquo;exp\u00e9rience d&rsquo;\u0153notourisme soit \u00e9galement accessible aux clients pr\u00e9sentant un handicap physique. De plus, la mise en place de certains de ces services a permis d&rsquo;am\u00e9liorer l&rsquo;exp\u00e9rience des autres clients \u00e9galement, qui peuvent ainsi b\u00e9n\u00e9ficier de services et d&rsquo;activit\u00e9s suppl\u00e9mentaires en plus de l&rsquo;offre \u00ab standard \u00bb. <\/p>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id1275_b96232-76 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1275_b96232-76 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1275_b96232-76 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1275_b96232-76 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1275_b96232-76 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1275_b96232-76 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1275_b96232-76 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1275_fd66a4-84 > .kt-inside-inner-col,.kadence-column1275_fd66a4-84 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1275_fd66a4-84 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1275_fd66a4-84 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1275_fd66a4-84 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1275_fd66a4-84 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1275_fd66a4-84{position:relative;}@media all and (max-width: 1024px){.kadence-column1275_fd66a4-84 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1275_fd66a4-84 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1275_fd66a4-84\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns1275_76cfc4-c1{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns1275_76cfc4-c1 .kt-button{font-weight:normal;font-style:normal;}.kt-btns1275_76cfc4-c1 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns1275_76cfc4-c1 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns1275_76cfc4-c1 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1275_76cfc4-c1 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns1275_76cfc4-c1 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns1275_76cfc4-c1 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1275_76cfc4-c1 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns1275_76cfc4-c1\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn1275_4ece5b-ca.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn1275_4ece5b-ca.kb-button{background:#9b2b55;}@media all and (max-width: 1024px){.kb-btn1275_4ece5b-ca.kb-button .kb-svg-icon-wrap{display:block;}}<\/style><a class=\"kb-button kt-button button kb-btn1275_4ece5b-ca kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/www.mtvveneto.it\/cantina\/ca-di-rajo\/%20https:\/\/www.cadirajo.it\/it\/#\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"kt-btn-inner-text\">Plus d&rsquo;informations<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"featured_media":5122,"template":"","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false},"innovation-area":[4,7],"region":[8],"class_list":["post-5146","case","type-case","status-publish","has-post-thumbnail","hentry","innovation-area-accessibility-and-inclusiveness","innovation-area-marketing-experiences-and-services","region-veneto"],"acf":[],"taxonomy_info":{"innovation-area":[{"value":4,"label":"Accessibility and Inclusiveness"},{"value":7,"label":"Marketing, Experiences and Services"}],"region":[{"value":8,"label":"Veneto"}]},"featured_image_src_large":["https:\/\/enotourproject.org\/wp-content\/uploads\/2024\/08\/place-holder-cases-v.jpg",288,188,false],"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/enotourproject.org\/fr\/wp-json\/wp\/v2\/case\/5146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enotourproject.org\/fr\/wp-json\/wp\/v2\/case"}],"about":[{"href":"https:\/\/enotourproject.org\/fr\/wp-json\/wp\/v2\/types\/case"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/enotourproject.org\/fr\/wp-json\/wp\/v2\/media\/5122"}],"wp:attachment":[{"href":"https:\/\/enotourproject.org\/fr\/wp-json\/wp\/v2\/media?parent=5146"}],"wp:term":[{"taxonomy":"innovation-area","embeddable":true,"href":"https:\/\/enotourproject.org\/fr\/wp-json\/wp\/v2\/innovation-area?post=5146"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/enotourproject.org\/fr\/wp-json\/wp\/v2\/region?post=5146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}