{"id":5140,"date":"2024-08-12T16:48:42","date_gmt":"2024-08-12T14:48:42","guid":{"rendered":"https:\/\/enotourproject.org\/case\/artcava\/"},"modified":"2026-07-21T18:07:49","modified_gmt":"2026-07-21T16:07:49","slug":"artcava","status":"publish","type":"case","link":"https:\/\/enotourproject.org\/ca\/case\/artcava\/","title":{"rendered":"ArtCava"},"content":{"rendered":"<style>.kb-row-layout-id1276_ac6c3b-36 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id1276_ac6c3b-36 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id1276_ac6c3b-36 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1276_ac6c3b-36{background-image:linear-gradient(135deg,var(--global-palette3) 3%,var(--global-palette4) 100%);}.kb-row-layout-id1276_ac6c3b-36 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1276_ac6c3b-36 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1276_ac6c3b-36 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1276_ac6c3b-36 aligncenter kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle\">\n<style>.kadence-column1276_542740-3f > .kt-inside-inner-col{display:flex;}.kadence-column1276_542740-3f > .kt-inside-inner-col,.kadence-column1276_542740-3f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1276_542740-3f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1276_542740-3f > .kt-inside-inner-col{flex-direction:column;align-items:center;}.kadence-column1276_542740-3f > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column1276_542740-3f > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column1276_542740-3f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1276_542740-3f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1276_542740-3f{position:relative;}@media all and (max-width: 1024px){.kadence-column1276_542740-3f > .kt-inside-inner-col{flex-direction:column;align-items:center;}}@media all and (max-width: 767px){.kadence-column1276_542740-3f > .kt-inside-inner-col{flex-direction:column;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1276_542740-3f\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1276_aeb57d-64, .wp-block-kadence-advancedheading.kt-adv-heading1276_aeb57d-64[data-kb-block=\"kb-adv-heading1276_aeb57d-64\"]{font-size:var(--global-kb-font-size-sm, 0.9rem);font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading1276_aeb57d-64 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1276_aeb57d-64[data-kb-block=\"kb-adv-heading1276_aeb57d-64\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h4 class=\"kt-adv-heading1276_aeb57d-64 wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading1276_aeb57d-64\">CAS D&#8217;INNOVACI\u00d3 &#8211; M\u00e0rqueting, Experi\u00e8ncies i Serveis<\/h4>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1276_197c94-f8, .wp-block-kadence-advancedheading.kt-adv-heading1276_197c94-f8[data-kb-block=\"kb-adv-heading1276_197c94-f8\"]{font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading1276_197c94-f8 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1276_197c94-f8[data-kb-block=\"kb-adv-heading1276_197c94-f8\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<h2 class=\"kt-adv-heading1276_197c94-f8 wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading1276_197c94-f8\">ArtCava: Enoturisme interactiu i experi\u00e8ncies personalitzades de Cava<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1276_82162a-e4, .wp-block-kadence-advancedheading.kt-adv-heading1276_82162a-e4[data-kb-block=\"kb-adv-heading1276_82162a-e4\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1276_82162a-e4[data-kb-block=\"kb-adv-heading1276_82162a-e4\"]{display:flex;gap:0.25em;align-items:center;}.wp-block-kadence-advancedheading.kt-adv-heading1276_82162a-e4[data-kb-block=\"kb-adv-heading1276_82162a-e4\"] .kb-adv-heading-icon svg{width:1em;height:1em;}.wp-block-kadence-advancedheading.kt-adv-heading1276_82162a-e4 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1276_82162a-e4[data-kb-block=\"kb-adv-heading1276_82162a-e4\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style><p class=\"kt-adv-heading1276_82162a-e4 wp-block-kadence-advancedheading kt-adv-heading-has-icon has-theme-palette9-color has-text-color\" data-kb-block=\"kb-adv-heading1276_82162a-e4\"><span class=\"kb-svg-icon-wrap kb-adv-heading-icon kb-svg-icon-fas_map-pin kb-adv-heading-icon-side-left\"><svg viewBox=\"0 0 288 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M112 316.94v156.69l22.02 33.02c4.75 7.12 15.22 7.12 19.97 0L176 473.63V316.94c-10.39 1.92-21.06 3.06-32 3.06s-21.61-1.14-32-3.06zM144 0C64.47 0 0 64.47 0 144s64.47 144 144 144 144-64.47 144-144S223.53 0 144 0zm0 76c-37.5 0-68 30.5-68 68 0 6.62-5.38 12-12 12s-12-5.38-12-12c0-50.73 41.28-92 92-92 6.62 0 12 5.38 12 12s-5.38 12-12 12z\"\/><\/svg><\/span><span class=\"kb-adv-text-inner\">Avinyonet del Pened\u00e8s, Barcelona, Espanya<\/span><\/p><\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id1276_0cc250-e8 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id1276_0cc250-e8 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id1276_0cc250-e8 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-none, 0rem );max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id1276_0cc250-e8 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1276_0cc250-e8 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1276_0cc250-e8 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1276_0cc250-e8 aligncenter has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column1276_9eaafe-12 > .kt-inside-inner-col,.kadence-column1276_9eaafe-12 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1276_9eaafe-12 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1276_9eaafe-12 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1276_9eaafe-12 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1276_9eaafe-12 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1276_9eaafe-12{position:relative;}@media all and (max-width: 1024px){.kadence-column1276_9eaafe-12 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1276_9eaafe-12 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1276_9eaafe-12\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1276_7012ad-a4 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1276_7012ad-a4 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:30px;border-top-right-radius:30px;border-bottom-right-radius:30px;border-bottom-left-radius:30px;padding-top:0px;padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:0px;padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-info-box1276_7012ad-a4 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1276_7012ad-a4 .kt-info-svg-icon-flip, .kt-info-box1276_7012ad-a4 .kt-blocks-info-box-number{font-size:20px;}.kt-info-box1276_7012ad-a4 .kt-blocks-info-box-media{color:var(--global-palette4, #2D3748);border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box1276_7012ad-a4 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box1276_7012ad-a4 .kt-infobox-textcontent h4.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1276_7012ad-a4 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette2, #2B6CB0);}.kt-info-box1276_7012ad-a4 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box1276_7012ad-a4 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box1276_7012ad-a4 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1276_7012ad-a4\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_calendar kt-info-svg-icon\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M0 0v2h7v-2h-7zm0 3v4.91c0 .05.04.09.09.09h6.81c.05 0 .09-.04.09-.09v-4.91h-7zm1 1h1v1h-1v-1zm2 0h1v1h-1v-1zm2 0h1v1h-1v-1zm-4 2h1v1h-1v-1zm2 0h1v1h-1v-1z\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><p class=\"kt-blocks-info-box-text\"><strong>Any d&#8217;inici<\/strong> : 2004<\/p><\/div><\/span><\/div>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1276_4eed8a-89 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1276_4eed8a-89 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:30px;border-top-right-radius:30px;border-bottom-right-radius:30px;border-bottom-left-radius:30px;padding-top:0px;padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:0px;padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-info-box1276_4eed8a-89 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1276_4eed8a-89 .kt-info-svg-icon-flip, .kt-info-box1276_4eed8a-89 .kt-blocks-info-box-number{font-size:20px;}.kt-info-box1276_4eed8a-89 .kt-blocks-info-box-media{color:var(--global-palette4, #2D3748);border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box1276_4eed8a-89 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box1276_4eed8a-89 .kt-infobox-textcontent h4.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1276_4eed8a-89 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette2, #2B6CB0);}.kt-info-box1276_4eed8a-89 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box1276_4eed8a-89 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box1276_4eed8a-89 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1276_4eed8a-89\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_people kt-info-svg-icon\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M5.5 0c-.51 0-.95.35-1.22.88.45.54.72 1.28.72 2.13 0 .29-.03.55-.09.81.19.11.38.19.59.19.83 0 1.5-.9 1.5-2s-.67-2-1.5-2zm-3 1c-.83 0-1.5.9-1.5 2s.67 2 1.5 2 1.5-.9 1.5-2-.67-2-1.5-2zm4.75 3.16c-.43.51-1.02.82-1.69.84.27.38.44.84.44 1.34v.66h2v-1.66c0-.52-.31-.97-.75-1.19zm-6.5 1c-.44.22-.75.67-.75 1.19v1.66h5v-1.66c0-.52-.31-.97-.75-1.19-.45.53-1.06.84-1.75.84s-1.3-.32-1.75-.84z\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><p class=\"kt-blocks-info-box-text\"><strong>Subjectes implicats<\/strong> : equip d&#8217;ArtCava, visitants, entusiastes del vi, comunitat local<\/p><\/div><\/span><\/div>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1276_de686d-35 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1276_de686d-35 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:30px;border-top-right-radius:30px;border-bottom-right-radius:30px;border-bottom-left-radius:30px;padding-top:0px;padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:0px;padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-info-box1276_de686d-35 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1276_de686d-35 .kt-info-svg-icon-flip, .kt-info-box1276_de686d-35 .kt-blocks-info-box-number{font-size:20px;}.kt-info-box1276_de686d-35 .kt-blocks-info-box-media{color:var(--global-palette4, #2D3748);border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box1276_de686d-35 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box1276_de686d-35 .kt-infobox-textcontent h4.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1276_de686d-35 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette2, #2B6CB0);}.kt-info-box1276_de686d-35 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box1276_de686d-35 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box1276_de686d-35 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1276_de686d-35\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_graph kt-info-svg-icon\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M7.03 0l-3.03 3-1-1-3 3.03 1 1 2-2.03 1 1 4-4-.97-1zm-7.03 7v1h8v-1h-8z\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><p class=\"kt-blocks-info-box-text\"><strong>\u00c0rea d&#8217;innovaci\u00f3<\/strong> : M\u00e0rqueting<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1276_998538-bf > .kt-inside-inner-col,.kadence-column1276_998538-bf > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1276_998538-bf > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1276_998538-bf > .kt-inside-inner-col{flex-direction:column;}.kadence-column1276_998538-bf > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1276_998538-bf > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1276_998538-bf{position:relative;}@media all and (max-width: 1024px){.kadence-column1276_998538-bf > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1276_998538-bf > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1276_998538-bf\"><div class=\"kt-inside-inner-col\"><style>.kb-image1276_94861f-5f .kb-image-has-overlay:after{opacity:0.3;}.kb-image1276_94861f-5f img.kb-img, .kb-image1276_94861f-5f .kb-img img{box-shadow:0px 0px 14px 0px rgba(0, 0, 0, 0.2);}<\/style>\n<div class=\"wp-block-kadence-image kb-image1276_94861f-5f\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/enotourproject.org\/wp-content\/uploads\/2024\/08\/place-holder-cases.jpg\" alt=\"\" class=\"kb-img wp-image-1945\" srcset=\"https:\/\/enotourproject.org\/wp-content\/uploads\/2024\/08\/place-holder-cases.jpg 400w, https:\/\/enotourproject.org\/wp-content\/uploads\/2024\/08\/place-holder-cases-300x300.jpg 300w, https:\/\/enotourproject.org\/wp-content\/uploads\/2024\/08\/place-holder-cases-150x150.jpg 150w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure><\/div>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id1276_9c791c-64 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id1276_9c791c-64 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id1276_9c791c-64 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1276_9c791c-64 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1276_9c791c-64 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1276_9c791c-64 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1276_9c791c-64 aligncenter wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column1276_09988f-e8 > .kt-inside-inner-col,.kadence-column1276_09988f-e8 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1276_09988f-e8 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1276_09988f-e8 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1276_09988f-e8 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1276_09988f-e8 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1276_09988f-e8{position:relative;}@media all and (max-width: 1024px){.kadence-column1276_09988f-e8 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1276_09988f-e8 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1276_09988f-e8\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1276_a69f01-72, .wp-block-kadence-advancedheading.kt-adv-heading1276_a69f01-72[data-kb-block=\"kb-adv-heading1276_a69f01-72\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1276_a69f01-72[data-kb-block=\"kb-adv-heading1276_a69f01-72\"]{display:flex;gap:0.25em;align-items:center;}.wp-block-kadence-advancedheading.kt-adv-heading1276_a69f01-72[data-kb-block=\"kb-adv-heading1276_a69f01-72\"] .kb-adv-heading-icon svg{width:1em;height:1em;}.wp-block-kadence-advancedheading.kt-adv-heading1276_a69f01-72[data-kb-block=\"kb-adv-heading1276_a69f01-72\"] .kb-adv-heading-icon{font-size:43px;margin-right:var(--global-kb-spacing-xxs, 0.5rem);}.wp-block-kadence-advancedheading.kt-adv-heading1276_a69f01-72 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1276_a69f01-72[data-kb-block=\"kb-adv-heading1276_a69f01-72\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style><h2 class=\"kt-adv-heading1276_a69f01-72 wp-block-kadence-advancedheading kt-adv-heading-has-icon has-theme-palette4-color has-text-color\" data-kb-block=\"kb-adv-heading1276_a69f01-72\"><span class=\"kb-svg-icon-wrap kb-adv-heading-icon kb-svg-icon-ic_minus kb-adv-heading-icon-side-left\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M0 0v2h8v-2h-8z\" transform=\"translate(0 3)\"\/><\/svg><\/span><span class=\"kb-adv-text-inner\"><strong>Objectius<\/strong><\/span><\/h2>\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1276_f28392-de .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1276_f28392-de .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:30px;border-top-right-radius:30px;border-bottom-right-radius:30px;border-bottom-left-radius:30px;background:var(--global-palette9, #ffffff);padding-top:0px;padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:0px;padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-info-box1276_f28392-de .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1276_f28392-de .kt-info-svg-icon-flip, .kt-info-box1276_f28392-de .kt-blocks-info-box-number{font-size:20px;}.kt-info-box1276_f28392-de .kt-blocks-info-box-media{color:var(--global-palette4, #2D3748);border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box1276_f28392-de .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box1276_f28392-de .kt-infobox-textcontent h4.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1276_f28392-de .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette2, #2B6CB0);}.kt-info-box1276_f28392-de .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box1276_f28392-de .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box1276_f28392-de .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1276_f28392-de\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_check kt-info-svg-icon\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M6.41 0l-.69.72-2.78 2.78-.81-.78-.72-.72-1.41 1.41.72.72 1.5 1.5.69.72.72-.72 3.5-3.5.72-.72-1.44-1.41z\" transform=\"translate(0 1)\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><p class=\"kt-blocks-info-box-text\">Oferir experi\u00e8ncies enotur\u00edstiques \u00faniques i personalitzades.<\/p><\/div><\/span><\/div>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1276_89d13a-e8 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1276_89d13a-e8 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:30px;border-top-right-radius:30px;border-bottom-right-radius:30px;border-bottom-left-radius:30px;background:var(--global-palette9, #ffffff);padding-top:0px;padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:0px;padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-info-box1276_89d13a-e8 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1276_89d13a-e8 .kt-info-svg-icon-flip, .kt-info-box1276_89d13a-e8 .kt-blocks-info-box-number{font-size:20px;}.kt-info-box1276_89d13a-e8 .kt-blocks-info-box-media{color:var(--global-palette4, #2D3748);border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box1276_89d13a-e8 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box1276_89d13a-e8 .kt-infobox-textcontent h4.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1276_89d13a-e8 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette2, #2B6CB0);}.kt-info-box1276_89d13a-e8 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box1276_89d13a-e8 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box1276_89d13a-e8 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1276_89d13a-e8\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_check kt-info-svg-icon\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M6.41 0l-.69.72-2.78 2.78-.81-.78-.72-.72-1.41 1.41.72.72 1.5 1.5.69.72.72-.72 3.5-3.5.72-.72-1.44-1.41z\" transform=\"translate(0 1)\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><p class=\"kt-blocks-info-box-text\">Involucrar els visitants a trav\u00e9s d&#8217;activitats interactives com ara la creaci\u00f3 del seu propi cava.<\/p><\/div><\/span><\/div>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1276_193e59-d5 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1276_193e59-d5 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);border-top-left-radius:30px;border-top-right-radius:30px;border-bottom-right-radius:30px;border-bottom-left-radius:30px;background:var(--global-palette9, #ffffff);padding-top:0px;padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:0px;padding-left:var(--global-kb-spacing-xs, 1rem);}.kt-info-box1276_193e59-d5 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1276_193e59-d5 .kt-info-svg-icon-flip, .kt-info-box1276_193e59-d5 .kt-blocks-info-box-number{font-size:20px;}.kt-info-box1276_193e59-d5 .kt-blocks-info-box-media{color:var(--global-palette4, #2D3748);border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box1276_193e59-d5 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box1276_193e59-d5 .kt-infobox-textcontent h4.kt-blocks-info-box-title{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1276_193e59-d5 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette2, #2B6CB0);}.kt-info-box1276_193e59-d5 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box1276_193e59-d5 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box1276_193e59-d5 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1276_193e59-d5\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-left kt-info-halign-left\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-ic_check kt-info-svg-icon\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M6.41 0l-.69.72-2.78 2.78-.81-.78-.72-.72-1.41 1.41.72.72 1.5 1.5.69.72.72-.72 3.5-3.5.72-.72-1.44-1.41z\" transform=\"translate(0 1)\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><p class=\"kt-blocks-info-box-text\">Generar la major part dels ingressos a trav\u00e9s d&#8217;activitats tur\u00edstiques.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id1276_4314ea-25 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1276_4314ea-25 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1276_4314ea-25 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1276_4314ea-25 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1276_4314ea-25 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1276_4314ea-25 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1276_4314ea-25 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-row kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1276_366b8c-16 > .kt-inside-inner-col,.kadence-column1276_366b8c-16 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1276_366b8c-16 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1276_366b8c-16 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1276_366b8c-16 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1276_366b8c-16 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1276_366b8c-16{position:relative;}@media all and (max-width: 1024px){.kadence-column1276_366b8c-16 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1276_366b8c-16 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1276_366b8c-16\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1276_ef9133-97, .wp-block-kadence-advancedheading.kt-adv-heading1276_ef9133-97[data-kb-block=\"kb-adv-heading1276_ef9133-97\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1276_ef9133-97[data-kb-block=\"kb-adv-heading1276_ef9133-97\"]{display:flex;gap:0.25em;align-items:center;}.wp-block-kadence-advancedheading.kt-adv-heading1276_ef9133-97[data-kb-block=\"kb-adv-heading1276_ef9133-97\"] .kb-adv-heading-icon svg{width:1em;height:1em;}.wp-block-kadence-advancedheading.kt-adv-heading1276_ef9133-97[data-kb-block=\"kb-adv-heading1276_ef9133-97\"] .kb-adv-heading-icon{font-size:43px;margin-right:var(--global-kb-spacing-xxs, 0.5rem);}.wp-block-kadence-advancedheading.kt-adv-heading1276_ef9133-97 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1276_ef9133-97[data-kb-block=\"kb-adv-heading1276_ef9133-97\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style><h2 class=\"kt-adv-heading1276_ef9133-97 wp-block-kadence-advancedheading kt-adv-heading-has-icon has-theme-palette4-color has-text-color\" data-kb-block=\"kb-adv-heading1276_ef9133-97\"><span class=\"kb-svg-icon-wrap kb-adv-heading-icon kb-svg-icon-ic_minus kb-adv-heading-icon-side-left\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M0 0v2h8v-2h-8z\" transform=\"translate(0 3)\"\/><\/svg><\/span><span class=\"kb-adv-text-inner\"><strong>Resum<\/strong><\/span><\/h2><\/div><\/div>\n\n\n<style>.kadence-column1276_2fb170-fb > .kt-inside-inner-col,.kadence-column1276_2fb170-fb > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1276_2fb170-fb > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1276_2fb170-fb > .kt-inside-inner-col{flex-direction:column;}.kadence-column1276_2fb170-fb > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1276_2fb170-fb > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1276_2fb170-fb{position:relative;}@media all and (max-width: 1024px){.kadence-column1276_2fb170-fb > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1276_2fb170-fb > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1276_2fb170-fb\"><div class=\"kt-inside-inner-col\">\n<p class=\"has-theme-palette-1-color has-text-color has-link-color wp-elements-1 wp-block-paragraph\">ArtCava destaca en la ind\u00fastria del turisme del vi pel seu enfocament innovador del m\u00e0rqueting i les experi\u00e8ncies personalitzades per als visitants. El celler ofereix activitats \u00faniques on els visitants poden crear el seu propi cava, produint tres ampolles per visitant. Aquest model interactiu \u00e9s gaireb\u00e9 \u00fanic en la ind\u00fastria del vi i ha demostrat ser un gran \u00e8xit, amb un 95% dels ingressos del celler provinents d&#8217;activitats tur\u00edstiques. L&#8217;enfocament d&#8217;ArtCava proporciona una experi\u00e8ncia immersiva per als amants del vi, convertint-lo en una destinaci\u00f3 privilegiada per a aquells que busquen una experi\u00e8ncia enotur\u00edstica pr\u00e0ctica i personalitzada.   <\/p>\n\n\n\n<p class=\"has-theme-palette-1-color has-text-color has-link-color wp-elements-2 wp-block-paragraph\">L&#8217;\u00e8xit del celler es basa en la creaci\u00f3 d&#8217;experi\u00e8ncies memorables i atractives que van m\u00e9s enll\u00e0 del tast de vins tradicional. Els visitants estan convidats a participar en tot el proc\u00e9s d&#8217;elaboraci\u00f3 del cava, des de la selecci\u00f3 del vi base fins al degollament, el dosatge i l&#8217;etiquetatge de les seves pr\u00f2pies ampolles. Aquest toc personalitzat no nom\u00e9s millora l&#8217;experi\u00e8ncia del visitant, sin\u00f3 que tamb\u00e9 fomenta una connexi\u00f3 m\u00e9s profunda amb la marca i el producte. L&#8217;esl\u00f2gan d&#8217;ArtCava, \u00abCultivant moments per crear records\u00bb, resumeix aquesta filosofia, emfatitzant la creaci\u00f3 de records duradors a trav\u00e9s d&#8217;experi\u00e8ncies \u00faniques.   <\/p>\n\n\n\n<p class=\"has-theme-palette-1-color has-text-color has-link-color wp-elements-3 wp-block-paragraph\">Celebrant 20 anys d&#8217;innovaci\u00f3 i creativitat, ArtCava s&#8217;ha consolidat com a pionera en el sector del turisme enol\u00f2gic. El seu model de negoci \u00fanic, centrat en experi\u00e8ncies interactives i personalitzades, la diferencia d&#8217;altres cellers i s&#8217;ha convertit en un referent d&#8217;\u00e8xit en la ind\u00fastria. <\/p>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id1276_29f8c6-3e > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1276_29f8c6-3e > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1276_29f8c6-3e > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1276_29f8c6-3e > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1276_29f8c6-3e > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1276_29f8c6-3e > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1276_29f8c6-3e alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-row kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1276_219be7-f9 > .kt-inside-inner-col,.kadence-column1276_219be7-f9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1276_219be7-f9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1276_219be7-f9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1276_219be7-f9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1276_219be7-f9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1276_219be7-f9{position:relative;}@media all and (max-width: 1024px){.kadence-column1276_219be7-f9 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1276_219be7-f9 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1276_219be7-f9\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1276_05405a-be, .wp-block-kadence-advancedheading.kt-adv-heading1276_05405a-be[data-kb-block=\"kb-adv-heading1276_05405a-be\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1276_05405a-be[data-kb-block=\"kb-adv-heading1276_05405a-be\"]{display:flex;gap:0.25em;align-items:center;}.wp-block-kadence-advancedheading.kt-adv-heading1276_05405a-be[data-kb-block=\"kb-adv-heading1276_05405a-be\"] .kb-adv-heading-icon svg{width:1em;height:1em;}.wp-block-kadence-advancedheading.kt-adv-heading1276_05405a-be[data-kb-block=\"kb-adv-heading1276_05405a-be\"] .kb-adv-heading-icon{font-size:43px;margin-right:var(--global-kb-spacing-xxs, 0.5rem);}.wp-block-kadence-advancedheading.kt-adv-heading1276_05405a-be mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1276_05405a-be[data-kb-block=\"kb-adv-heading1276_05405a-be\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style><h2 class=\"kt-adv-heading1276_05405a-be wp-block-kadence-advancedheading kt-adv-heading-has-icon has-theme-palette4-color has-text-color\" data-kb-block=\"kb-adv-heading1276_05405a-be\"><span class=\"kb-svg-icon-wrap kb-adv-heading-icon kb-svg-icon-ic_minus kb-adv-heading-icon-side-left\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M0 0v2h8v-2h-8z\" transform=\"translate(0 3)\"\/><\/svg><\/span><span class=\"kb-adv-text-inner\"><strong>Dificultats<\/strong><\/span><\/h2><\/div><\/div>\n\n\n<style>.kadence-column1276_3af2fb-e4 > .kt-inside-inner-col,.kadence-column1276_3af2fb-e4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1276_3af2fb-e4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1276_3af2fb-e4 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1276_3af2fb-e4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1276_3af2fb-e4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1276_3af2fb-e4{position:relative;}@media all and (max-width: 1024px){.kadence-column1276_3af2fb-e4 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1276_3af2fb-e4 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1276_3af2fb-e4\"><div class=\"kt-inside-inner-col\">\n<ul class=\"wp-block-list has-theme-palette-1-color has-text-color has-link-color wp-elements-4\">\n<li>Mantenir alts nivells de personalitzaci\u00f3 i qualitat amb l&#8217;augment del nombre de visitants.<\/li>\n\n\n\n<li>Equilibrar les demandes operatives de la producci\u00f3 de vi amb les activitats tur\u00edstiques.<\/li>\n\n\n\n<li>Innovant cont\u00ednuament per mantenir l&#8217;experi\u00e8ncia del visitant fresca i atractiva.<\/li>\n<\/ul>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id1276_758833-8b > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1276_758833-8b > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1276_758833-8b > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1276_758833-8b > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1276_758833-8b > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1276_758833-8b > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1276_758833-8b alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-row kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1276_03be31-72 > .kt-inside-inner-col,.kadence-column1276_03be31-72 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1276_03be31-72 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1276_03be31-72 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1276_03be31-72 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1276_03be31-72 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1276_03be31-72{position:relative;}@media all and (max-width: 1024px){.kadence-column1276_03be31-72 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1276_03be31-72 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1276_03be31-72\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1276_6172c7-f9, .wp-block-kadence-advancedheading.kt-adv-heading1276_6172c7-f9[data-kb-block=\"kb-adv-heading1276_6172c7-f9\"]{font-style:normal;color:#9b2b55;}.wp-block-kadence-advancedheading.kt-adv-heading1276_6172c7-f9[data-kb-block=\"kb-adv-heading1276_6172c7-f9\"]{display:flex;gap:0.25em;align-items:center;}.wp-block-kadence-advancedheading.kt-adv-heading1276_6172c7-f9[data-kb-block=\"kb-adv-heading1276_6172c7-f9\"] .kb-adv-heading-icon svg{width:1em;height:1em;}.wp-block-kadence-advancedheading.kt-adv-heading1276_6172c7-f9[data-kb-block=\"kb-adv-heading1276_6172c7-f9\"] .kb-adv-heading-icon{font-size:43px;margin-right:var(--global-kb-spacing-xxs, 0.5rem);}.wp-block-kadence-advancedheading.kt-adv-heading1276_6172c7-f9 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1276_6172c7-f9[data-kb-block=\"kb-adv-heading1276_6172c7-f9\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style><h2 class=\"kt-adv-heading1276_6172c7-f9 wp-block-kadence-advancedheading kt-adv-heading-has-icon\" data-kb-block=\"kb-adv-heading1276_6172c7-f9\"><span class=\"kb-svg-icon-wrap kb-adv-heading-icon kb-svg-icon-ic_minus kb-adv-heading-icon-side-left\"><svg viewBox=\"0 0 8 8\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M0 0v2h8v-2h-8z\" transform=\"translate(0 3)\"\/><\/svg><\/span><span class=\"kb-adv-text-inner\"><strong>Resultats<\/strong><\/span><\/h2><\/div><\/div>\n\n\n<style>.kadence-column1276_a64b66-06 > .kt-inside-inner-col,.kadence-column1276_a64b66-06 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1276_a64b66-06 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1276_a64b66-06 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1276_a64b66-06 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1276_a64b66-06 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1276_a64b66-06{position:relative;}@media all and (max-width: 1024px){.kadence-column1276_a64b66-06 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1276_a64b66-06 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1276_a64b66-06\"><div class=\"kt-inside-inner-col\">\n<ul class=\"wp-block-list\">\n<li>Alta satisfacci\u00f3 i participaci\u00f3 dels visitants.<\/li>\n\n\n\n<li>Generaci\u00f3 significativa d&#8217;ingressos derivats de les activitats tur\u00edstiques.<\/li>\n\n\n\n<li>Fort reconeixement de marca i fidelitzaci\u00f3 entre els visitants.<\/li>\n<\/ul>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id1276_ee2a8a-82 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1276_ee2a8a-82 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1276_ee2a8a-82 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1276_ee2a8a-82 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1276_ee2a8a-82 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1276_ee2a8a-82 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1276_ee2a8a-82 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1276_12ec1f-03 > .kt-inside-inner-col,.kadence-column1276_12ec1f-03 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1276_12ec1f-03 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1276_12ec1f-03 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1276_12ec1f-03 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1276_12ec1f-03 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1276_12ec1f-03{position:relative;}@media all and (max-width: 1024px){.kadence-column1276_12ec1f-03 > .kt-inside-inner-col{flex-direction:column;}}@media all and (max-width: 767px){.kadence-column1276_12ec1f-03 > .kt-inside-inner-col{flex-direction:column;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1276_12ec1f-03\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kb-btns1276_ca597e-a4{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns1276_ca597e-a4 .kt-button{font-weight:normal;font-style:normal;}.kt-btns1276_ca597e-a4 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns1276_ca597e-a4 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns1276_ca597e-a4 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1276_ca597e-a4 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns1276_ca597e-a4 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns1276_ca597e-a4 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1276_ca597e-a4 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns1276_ca597e-a4\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn1276_d5040e-74.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn1276_d5040e-74.kb-button{background:#9b2b55;}@media all and (max-width: 1024px){.kb-btn1276_d5040e-74.kb-button .kb-svg-icon-wrap{display:block;}}<\/style><a class=\"kb-button kt-button button kb-btn1276_d5040e-74 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\" href=\"https:\/\/artcava.com\/en\/\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"kt-btn-inner-text\">M\u00e9s informaci\u00f3<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"featured_media":5124,"template":"","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false},"innovation-area":[7],"region":[9],"class_list":["post-5140","case","type-case","status-publish","has-post-thumbnail","hentry","innovation-area-marketing-experiences-and-services","region-catalonia"],"acf":[],"taxonomy_info":{"innovation-area":[{"value":7,"label":"Marketing, Experiences and Services"}],"region":[{"value":9,"label":"Catalonia"}]},"featured_image_src_large":["https:\/\/enotourproject.org\/wp-content\/uploads\/2024\/08\/place-holder-cases-v.jpg",288,188,false],"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/enotourproject.org\/ca\/wp-json\/wp\/v2\/case\/5140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enotourproject.org\/ca\/wp-json\/wp\/v2\/case"}],"about":[{"href":"https:\/\/enotourproject.org\/ca\/wp-json\/wp\/v2\/types\/case"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/enotourproject.org\/ca\/wp-json\/wp\/v2\/media\/5124"}],"wp:attachment":[{"href":"https:\/\/enotourproject.org\/ca\/wp-json\/wp\/v2\/media?parent=5140"}],"wp:term":[{"taxonomy":"innovation-area","embeddable":true,"href":"https:\/\/enotourproject.org\/ca\/wp-json\/wp\/v2\/innovation-area?post=5140"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/enotourproject.org\/ca\/wp-json\/wp\/v2\/region?post=5140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}